{"id":2987,"date":"2018-06-02T21:37:31","date_gmt":"2018-06-02T19:37:31","guid":{"rendered":"https:\/\/ctrc9x8i6indg0vl.myfritz.net:85\/wordpress\/?p=2987"},"modified":"2018-06-03T08:38:46","modified_gmt":"2018-06-03T06:38:46","slug":"2987","status":"publish","type":"post","link":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/2987\/","title":{"rendered":"3. Zahn, hinknien und hinstellen"},"content":{"rendered":"<p>Kai stellt fr\u00fch Lorenas Bett eine Etage tiefer. Sie ist darin auf den Knien und st\u00fctzt sich ab oder kniet freih\u00e4ndig.<\/p>\n<p>Im Wohnzimmer r\u00e4umt sie den DVD Schrank aus.<\/p>\n<p>Ich f\u00fchle w\u00e4hrend dem Z\u00e4hne Putzen in ihren Mund und entdecke, dass der 3. Zahn durch ist!! Eckzahn oben links. Man sieht eine kleine wei\u00dfe Spitze. Keine Ahnung wann die durch ist&#8230;aber wir hatten eine unruhige Nacht im Urlaub&#8230;oder vielleicht hatte auch das Fieber vor knapp 2 Wochen was damit zu tun&#8230;Keine Ahnung. Aber wir freuen uns, dass Zahn nr. 3 zu sehen ist.<\/p>\n<p>Wir legen sie zum Vormittagsschlaf ins Bett, da sie bald wach war. Sie schl\u00e4ft 1,5 Stunden.<\/p>\n<p>Ich bin den ganzen Tag damit besch\u00e4ftigt sie zu halten und aufzupassen. Sie zieht sich an den Schubladen im Wohnzimmer in den Stand. In den Schubladen interessiert sie sich nat\u00fcrlich f\u00fcr die Kabel.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-2986\" src=\"https:\/\/ctrc9x8i6indg0vl.myfritz.net:85\/wordpress\/wp-content\/uploads\/2018\/06\/20180602_21225736039383822855995.jpg\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-content\/uploads\/2018\/06\/20180602_21225736039383822855995.jpg 1000w, https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-content\/uploads\/2018\/06\/20180602_21225736039383822855995-100x100.jpg 100w, https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-content\/uploads\/2018\/06\/20180602_21225736039383822855995-240x240.jpg 240w, https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-content\/uploads\/2018\/06\/20180602_21225736039383822855995-768x768.jpg 768w, https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-content\/uploads\/2018\/06\/20180602_21225736039383822855995-960x960.jpg 960w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kai stellt fr\u00fch Lorenas Bett eine Etage tiefer. Sie ist darin auf den Knien und st\u00fctzt sich ab oder kniet freih\u00e4ndig. Im Wohnzimmer r\u00e4umt sie den DVD Schrank aus. Ich f\u00fchle w\u00e4hrend dem Z\u00e4hne Putzen in ihren Mund und entdecke, dass der 3. Zahn durch ist!! Eckzahn oben links. Man sieht eine kleine wei\u00dfe Spitze. &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/2987\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e3. Zahn, hinknien und hinstellen\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[24],"tags":[],"_links":{"self":[{"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/posts\/2987"}],"collection":[{"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/comments?post=2987"}],"version-history":[{"count":2,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/posts\/2987\/revisions"}],"predecessor-version":[{"id":2989,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/posts\/2987\/revisions\/2989"}],"wp:attachment":[{"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/media?parent=2987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/categories?post=2987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/tags?post=2987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}