{"id":2888,"date":"2018-04-20T20:11:07","date_gmt":"2018-04-20T18:11:07","guid":{"rendered":"https:\/\/ctrc9x8i6indg0vl.myfritz.net:85\/wordpress\/?p=2888"},"modified":"2018-04-23T16:11:19","modified_gmt":"2018-04-23T14:11:19","slug":"fremdeln","status":"publish","type":"post","link":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/fremdeln\/","title":{"rendered":"Fremdeln"},"content":{"rendered":"<p>Abends kommen Tuncay und Theresa zu Besuch und Lorena fremdelt zum ersten Mal. Als sie Tuncay (T\u00fcrke, viele schwarze Haare) sieht muss sie zum Weinen anfangen und als erst Kai und ich sie hochnehme beruhigt sie sich gar nicht und klammert sich richtig fest an uns. Es hilft dann, dass ich mit ihr in ihr Zimmer gehe und singe dann beruhigt sie sich wieder. Sp\u00e4ter sitzen wir zusammen am Tisch und sie schaut Tuncay an und alles ist gut. Sie isst heute sogar richtig gut 50g Gramm Abendbrei.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abends kommen Tuncay und Theresa zu Besuch und Lorena fremdelt zum ersten Mal. Als sie Tuncay (T\u00fcrke, viele schwarze Haare) sieht muss sie zum Weinen anfangen und als erst Kai und ich sie hochnehme beruhigt sie sich gar nicht und klammert sich richtig fest an uns. Es hilft dann, dass ich mit ihr in ihr &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/fremdeln\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eFremdeln\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[24],"tags":[],"_links":{"self":[{"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/posts\/2888"}],"collection":[{"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/comments?post=2888"}],"version-history":[{"count":1,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/posts\/2888\/revisions"}],"predecessor-version":[{"id":2889,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/posts\/2888\/revisions\/2889"}],"wp:attachment":[{"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/media?parent=2888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/categories?post=2888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cokalosa.xkpnc7d6bisxm3b6.myfritz.net\/blog\/wp-json\/wp\/v2\/tags?post=2888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}